{"id":4491,"date":"2022-12-14T15:10:24","date_gmt":"2022-12-14T14:10:24","guid":{"rendered":"http:\/\/wp.pe-becker.de\/projekte\/110-3-strassenausbau-vogtpesch-m250-pdf\/"},"modified":"2022-12-14T15:10:24","modified_gmt":"2022-12-14T14:10:24","slug":"110-3-strassenausbau-vogtpesch-m250-pdf","status":"inherit","type":"attachment","link":"https:\/\/pe-becker.de\/projekte\/110-3-strassenausbau-vogtpesch-m250-pdf\/","title":{"rendered":"110-3-Strassenausbau-Vogtpesch-M250.pdf"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-4491","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250.pdf'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"108\" src=\"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250-pdf-300x108.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"full":{"file":"110-3-Strassenausbau-Vogtpesch-M250-pdf.jpg","width":6307,"height":2267,"mime_type":"application\/pdf","source_url":"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250-pdf.jpg"},"medium":{"file":"110-3-Strassenausbau-Vogtpesch-M250-pdf-300x108.jpg","width":300,"height":108,"filesize":12123,"mime_type":"image\/jpeg","source_url":"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250-pdf-300x108.jpg"},"large":{"file":"110-3-Strassenausbau-Vogtpesch-M250-pdf-1024x368.jpg","width":1024,"height":368,"filesize":92310,"mime_type":"image\/jpeg","source_url":"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250-pdf-1024x368.jpg"},"thumbnail":{"file":"110-3-Strassenausbau-Vogtpesch-M250-pdf-150x54.jpg","width":150,"height":54,"filesize":6041,"mime_type":"image\/jpeg","source_url":"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250-pdf-150x54.jpg"}},"filesize":3622300},"post":null,"source_url":"https:\/\/pe-becker.de\/projekte\/wp-content\/uploads\/sites\/4\/item_230\/110-3-Strassenausbau-Vogtpesch-M250.pdf","_links":{"self":[{"href":"https:\/\/pe-becker.de\/projekte\/wp-json\/wp\/v2\/media\/4491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pe-becker.de\/projekte\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pe-becker.de\/projekte\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pe-becker.de\/projekte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pe-becker.de\/projekte\/wp-json\/wp\/v2\/comments?post=4491"}]}}